{"id":1070,"date":"2021-05-08T19:24:29","date_gmt":"2021-05-08T19:24:29","guid":{"rendered":"http:\/\/nachoescartin.es\/?p=1070"},"modified":"2021-05-08T19:24:29","modified_gmt":"2021-05-08T19:24:29","slug":"breve-tratado-de-la-estupidez-humana-de-ricardo-moreno-castillo","status":"publish","type":"post","link":"https:\/\/nachoescartin.es\/an\/breve-tratado-de-la-estupidez-humana-de-ricardo-moreno-castillo\/","title":{"rendered":"\u201cBreve tratado de la estupidez humana\u201d de Ricardo Moreno Castillo"},"content":{"rendered":"<p>Recomendaron este librico en La Ventana de Francino, en la Cadena SER, y por eso lo compr\u00e9. Este breve tratado va de lo que va: de c\u00f3mo identificar la estupidez, c\u00f3mo reconocerla en uno mismo y c\u00f3mo huir de ella, a ser posible. El autor es profesor y doctor en filosof\u00eda, y sus reflexiones se asientan en sugerentes citas de fil\u00f3sofos y escritores como Unamuno, Twain, Voltaire o Arendt, entre otros.<\/p>\n<p>Es un librico porque es peque\u00f1o y corto, con apenas 100 p\u00e1ginas editadas por F\u00f3rcola. Algunas de las propuestas que plantea para luchar contra la estupidez me parecen sugerentes: cultivar aficiones tranquilas, la memoria, la lectura y el estudio (sobre todo historia para evitar repetir errores y filosof\u00eda para aprender de quienes ya han pensado antes que nosotros) y conocer nuestros propios l\u00edmites. La que menos me convence es la prudencia en la implicaci\u00f3n en la vida p\u00fablica, ya que considero que la pasi\u00f3n en las luchas no ri\u00f1e con la serenidad, la inteligencia y el acierto.<\/p>\n<p>Se trata, en definitiva, de no dejar el mundo peor de lo que est\u00e1; de intentar juntarnos con personas con las que merezca la pena estar e incluso emular; de huir de las est\u00fapidas y, especialmente, huir de la discusi\u00f3n para refutar certezas por todos asumidas, pero que algunos tontos cuestionan. El autor sostiene que la estupidez es m\u00e1s da\u00f1ina que la maldad pero que no son incompatibles.<\/p>\n<p>Ya que \u201cun hombre sabio nunca puede estar satisfecho con lo que sabe\u201d (en sus propias palabras), invito al autor a leer, estudiar y aprender m\u00e1s sobre feminismo, animalismo y otras luchas por el bien com\u00fan, para abordarlas con m\u00e1s tino y, as\u00ed, evitar caer en burlas y estigmas poco acertados.<\/p>","protected":false},"excerpt":{"rendered":"<p>Recomendaron este librico en La Ventana de Francino, en la Cadena SER, y por eso lo compr\u00e9. Este breve tratado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[26],"tags":[185,436,437,218,438,439,133,440],"class_list":["post-1070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultivando","tag-ensayo","tag-estudio","tag-estupidez","tag-filosofia","tag-inteligencia","tag-leer","tag-libro","tag-tontos"],"_links":{"self":[{"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/posts\/1070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/comments?post=1070"}],"version-history":[{"count":0,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/posts\/1070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/media\/1071"}],"wp:attachment":[{"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/media?parent=1070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/categories?post=1070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nachoescartin.es\/an\/wp-json\/wp\/v2\/tags?post=1070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}